{"id":3092,"date":"2022-09-05T10:11:53","date_gmt":"2022-09-05T13:11:53","guid":{"rendered":"https:\/\/comunidadefidelidade.com\/site\/?p=3092"},"modified":"2022-09-08T14:54:48","modified_gmt":"2022-09-08T17:54:48","slug":"roteiro-da-semana-de-12-a-18-de-setembro-de-2022-tema-jesus-e-a-porta","status":"publish","type":"post","link":"https:\/\/comunidadefidelidade.com\/site\/roteiro-da-semana-de-12-a-18-de-setembro-de-2022-tema-jesus-e-a-porta\/","title":{"rendered":"Roteiro da semana: De 12 a 18 de setembro de 2022 &#8211; Tema: Jesus \u00e9 a porta"},"content":{"rendered":"\n<p><strong>Ol\u00e1 L\u00edderes e auxiliares. Deus aben\u00e7oe sua miss\u00e3o. Visualize ou baixe o Roteiro da reuni\u00e3o de C\u00e9lula.<\/strong><\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/comunidadefidelidade.com\/site\/wp-content\/uploads\/2022\/09\/ROTEIRO-DA-REUNIAO-DE-CELULA-De-12-a-18-de-setembro-de-2022.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incorporado de Incorporado de ROTEIRO-DA-REUNIAO-DE-CELULA-De-12-a-18-de-setembro-de-2022..\"><\/object><a id=\"wp-block-file--media-fd1ff71f-96d7-43ec-9912-ff00b01f69eb\" href=\"https:\/\/comunidadefidelidade.com\/site\/wp-content\/uploads\/2022\/09\/ROTEIRO-DA-REUNIAO-DE-CELULA-De-12-a-18-de-setembro-de-2022.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">ROTEIRO-DA-REUNIAO-DE-CELULA-De-12-a-18-de-setembro-de-2022<\/a><a href=\"https:\/\/comunidadefidelidade.com\/site\/wp-content\/uploads\/2022\/09\/ROTEIRO-DA-REUNIAO-DE-CELULA-De-12-a-18-de-setembro-de-2022.pdf\" class=\"wp-block-file__button\" download aria-describedby=\"wp-block-file--media-fd1ff71f-96d7-43ec-9912-ff00b01f69eb\">Baixar<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1 L\u00edderes e auxiliares. Deus aben\u00e7oe sua miss\u00e3o. Visualize ou baixe o Roteiro da reuni\u00e3o de C\u00e9lula.<\/p>\n","protected":false},"author":1,"featured_media":2635,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-3092","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-roteiros","category-20","description-off"],"_links":{"self":[{"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/posts\/3092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/comments?post=3092"}],"version-history":[{"count":1,"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/posts\/3092\/revisions"}],"predecessor-version":[{"id":3094,"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/posts\/3092\/revisions\/3094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/media\/2635"}],"wp:attachment":[{"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/media?parent=3092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/categories?post=3092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/tags?post=3092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}