{"id":3124,"date":"2022-09-27T13:21:05","date_gmt":"2022-09-27T16:21:05","guid":{"rendered":"https:\/\/comunidadefidelidade.com\/site\/?p=3124"},"modified":"2022-09-27T13:21:06","modified_gmt":"2022-09-27T16:21:06","slug":"roteiro-da-semana-de-03-a-09-de-outubro-de-2022-serie-tema-segundo-mandamento-nao-tomaras-o-nome-de-deus-em-vao","status":"publish","type":"post","link":"https:\/\/comunidadefidelidade.com\/site\/roteiro-da-semana-de-03-a-09-de-outubro-de-2022-serie-tema-segundo-mandamento-nao-tomaras-o-nome-de-deus-em-vao\/","title":{"rendered":"Roteiro da semana: De 03 a 09 de outubro de 2022 &#8211; S\u00e9rie \/ Tema: SEGUNDO MANDAMENTO \u2013 N\u00e3o tomar\u00e1s o Nome de Deus em v\u00e3o"},"content":{"rendered":"\n<p><strong>Ol\u00e1 L\u00edderes e auxiliares. Deus aben\u00e7oe sua miss\u00e3o. Visualize ou baixe o Roteiro da reuni\u00e3o de C\u00e9lula.<\/strong><\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/comunidadefidelidade.com\/site\/wp-content\/uploads\/2022\/09\/ROTEIRO-DA-REUNIAO-DE-CELULA-De-03-a-09-de-outubro-de-2022.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incorporado de Incorporado de ROTEIRO-DA-REUNIAO-DE-CELULA-De-03-a-09-de-outubro-de-2022..\"><\/object><a id=\"wp-block-file--media-dcbe0bc7-2844-4914-874c-11d8d2572ab2\" href=\"https:\/\/comunidadefidelidade.com\/site\/wp-content\/uploads\/2022\/09\/ROTEIRO-DA-REUNIAO-DE-CELULA-De-03-a-09-de-outubro-de-2022.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">ROTEIRO-DA-REUNIAO-DE-CELULA-De-03-a-09-de-outubro-de-2022<\/a><a href=\"https:\/\/comunidadefidelidade.com\/site\/wp-content\/uploads\/2022\/09\/ROTEIRO-DA-REUNIAO-DE-CELULA-De-03-a-09-de-outubro-de-2022.pdf\" class=\"wp-block-file__button\" download aria-describedby=\"wp-block-file--media-dcbe0bc7-2844-4914-874c-11d8d2572ab2\">Baixar<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1 L\u00edderes e auxiliares. Deus aben\u00e7oe sua miss\u00e3o. Visualize ou baixe o Roteiro da reuni\u00e3o de C\u00e9lula.<\/p>\n","protected":false},"author":1,"featured_media":2635,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-3124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-roteiros","category-20","description-off"],"_links":{"self":[{"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/posts\/3124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/comments?post=3124"}],"version-history":[{"count":1,"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/posts\/3124\/revisions"}],"predecessor-version":[{"id":3126,"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/posts\/3124\/revisions\/3126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/media\/2635"}],"wp:attachment":[{"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/media?parent=3124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/categories?post=3124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/tags?post=3124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}