{"id":4130,"date":"2024-04-01T15:46:56","date_gmt":"2024-04-01T18:46:56","guid":{"rendered":"https:\/\/comunidadefidelidade.com\/site\/?p=4130"},"modified":"2024-04-01T15:46:57","modified_gmt":"2024-04-01T18:46:57","slug":"roteiro-da-semana-de-01-a-07-de-abril-de-2024-tema-maria-mae-de-misericordia","status":"publish","type":"post","link":"https:\/\/comunidadefidelidade.com\/site\/roteiro-da-semana-de-01-a-07-de-abril-de-2024-tema-maria-mae-de-misericordia\/","title":{"rendered":"Roteiro da semana: De 01 a 07 de Abril de 2024 &#8211; Tema: Maria, M\u00e3e de Miseric\u00f3rdia"},"content":{"rendered":"\n<p><strong><strong>Ol\u00e1 L\u00edderes e auxiliares. Deus aben\u00e7oe sua miss\u00e3o. Visualize ou baixe o Roteiro da reuni\u00e3o de C\u00e9lula.<\/strong><\/strong><\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/comunidadefidelidade.com\/site\/wp-content\/uploads\/2024\/04\/ROTEIRO-DA-REUNIAO-DE-CELULA-De-01-a-07-de-Abril-de-2024.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incorporado de ROTEIRO-DA-REUNIAO-DE-CELULA-De-01-a-07-de-Abril-de-2024.\"><\/object><a id=\"wp-block-file--media-fa53e392-eb6a-4648-91ec-e2034130a3b1\" href=\"https:\/\/comunidadefidelidade.com\/site\/wp-content\/uploads\/2024\/04\/ROTEIRO-DA-REUNIAO-DE-CELULA-De-01-a-07-de-Abril-de-2024.pdf\">ROTEIRO-DA-REUNIAO-DE-CELULA-De-01-a-07-de-Abril-de-2024<\/a><a href=\"https:\/\/comunidadefidelidade.com\/site\/wp-content\/uploads\/2024\/04\/ROTEIRO-DA-REUNIAO-DE-CELULA-De-01-a-07-de-Abril-de-2024.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-fa53e392-eb6a-4648-91ec-e2034130a3b1\">Baixar<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1 L\u00edderes e auxiliares. Deus aben\u00e7oe sua miss\u00e3o. Visualize ou baixe o Roteiro da reuni\u00e3o de C\u00e9lula.<\/p>\n","protected":false},"author":1,"featured_media":4077,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-4130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-roteiros","category-20","description-off"],"_links":{"self":[{"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/posts\/4130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/comments?post=4130"}],"version-history":[{"count":2,"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/posts\/4130\/revisions"}],"predecessor-version":[{"id":4213,"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/posts\/4130\/revisions\/4213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/media\/4077"}],"wp:attachment":[{"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/media?parent=4130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/categories?post=4130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunidadefidelidade.com\/site\/wp-json\/wp\/v2\/tags?post=4130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}